{"id":6808,"date":"2026-06-20T13:13:19","date_gmt":"2026-06-20T11:13:19","guid":{"rendered":"https:\/\/zampieravecchia.it\/4-stunden-von-imola-2026-european-le-mans-series\/"},"modified":"2026-07-15T00:21:14","modified_gmt":"2026-07-14T22:21:14","slug":"4-stunden-von-imola-2026-european-le-mans-series","status":"publish","type":"post","link":"https:\/\/zampieravecchia.it\/de\/4-stunden-von-imola-2026-european-le-mans-series\/","title":{"rendered":"4 Stunden von Imola 2026: Die European Le Mans Series kehrt zum Autodromo Enzo e Dino Ferrari zur\u00fcck"},"content":{"rendered":"<p>Vom Autodromo in Imola aus, bequem auf der Trib\u00fcne sitzend, betrachte ich das Schauspiel voller Bewunderung und stelle mir eine fast banale Frage: \u201eAber wie schaffen sie es nur, sich auszuweichen?&#8220; Ich sehe die Wagen mit irrwitziger Geschwindigkeit vorbeirasen und dennoch mit einer Selbstverst\u00e4ndlichkeit auf dem Asphalt kleben, die den Gesetzen der Physik trotzt. F\u00fcr Neulinge in diesem Bereich ist die <strong>European Le Mans Series in Imola<\/strong>, auch bekannt als <strong>4 Stunden von Imola<\/strong>, einer der Termine einer europ\u00e4ischen Meisterschaft, die \u00fcber die sch\u00f6nsten Rennstrecken des Kontinents f\u00fchrt. Es ist kein reines Geschwindigkeitsrennen, sondern eine echte Ausdauerpr\u00fcfung.<\/p>\n<figure class=\"wp-caption aligncenter\" style=\"max-width: 678px;\">\n<img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-6579\" src=\"https:\/\/zampieravecchia.it\/wp-content\/uploads\/2026\/06\/4-ore-imola-2026-european-le-mans-series-partenza.jpg\" alt=\"Start der 4 Stunden von Imola 2026: die Prototypen der European Le Mans Series auf der Rennstrecke Enzo e Dino Ferrari\" width=\"678\" height=\"452\" srcset=\"https:\/\/zampieravecchia.it\/wp-content\/uploads\/2026\/06\/4-ore-imola-2026-european-le-mans-series-partenza.jpg 678w, https:\/\/zampieravecchia.it\/wp-content\/uploads\/2026\/06\/4-ore-imola-2026-european-le-mans-series-partenza-300x200.jpg 300w, https:\/\/zampieravecchia.it\/wp-content\/uploads\/2026\/06\/4-ore-imola-2026-european-le-mans-series-partenza-600x400.jpg 600w\" sizes=\"(max-width: 678px) 100vw, 678px\" \/><figcaption class=\"wp-caption-text\">Der Start der 4 Stunden von Imola auf der Rennstrecke Enzo e Dino Ferrari.<\/figcaption><\/figure>\n<p>Die Wagen, die sich auf der Strecke messen, versuchen die Messlatte h\u00f6her zu legen und auf h\u00f6chstem Niveau zu konkurrieren, mit Blick auf die legend\u00e4ren <strong>24 Stunden von Le Mans<\/strong>, einen der H\u00f6hepunkte des <a href=\"https:\/\/zampieravecchia.it\/de\/fia-wec-2026-imola\/\">weltweiten Langstrecken-Motorsports<\/a>. Die Etappe der <strong>ELMS von Imola 2026<\/strong>, die einzige italienische Station des Kalenders, ist f\u00fcr den <strong>4. und 5. Juli 2026<\/strong> angesetzt.<\/p>\n<h2>Die 4 Stunden von Imola: Wie das Langstreckenrennen funktioniert<\/h2>\n<p>Kommen wir zum eigentlichen Wettbewerb. Es handelt sich um ein prestigetr\u00e4chtiges Langstreckenrennen, bei dem sich vier Fahrzeugklassen auf der Strecke messen: <strong>LMP2<\/strong>, <strong>LMP2 Pro\/Am<\/strong>, <strong>LMP3<\/strong> (Rennprototypen) und <strong>LMGT3<\/strong> (Gran-Turismo-Wagen). Anders als bei einem klassischen Formel-1-Rennen, bei dem gewinnt, wer nach einer festgelegten Anzahl von Runden die Ziellinie \u00fcberquert, besteht das Ziel hier darin, innerhalb eines Zeitlimits von <strong>4 Stunden<\/strong> die gr\u00f6\u00dftm\u00f6gliche Distanz zur\u00fcckzulegen.<\/p>\n<p>Die Fahrer entlang der <strong>4.909 Meter langen Strecke<\/strong> gegeneinander antreten zu sehen, ist ein wahnsinniges Erlebnis. Sagen wir es ruhig: Das <strong>Autodromo Internazionale Enzo e Dino Ferrari<\/strong> ist wahrlich kein Spaziergang, sondern eine der anspruchsvollsten Rennstrecken \u00fcberhaupt. Anders als viele moderne Kurse, die mit weiten asphaltierten Auslaufzonen angelegt sind, beh\u00e4lt die Strecke von Imola ein Layout bei, das den nat\u00fcrlichen Wellen des Gel\u00e4ndes folgt.<\/p>\n<p>Es ist eine Strecke mit altem Charme, <strong>\u201eold style&#8220;<\/strong>, mit vielen Steigungswechseln und blinden Kurven, die den Fahrern am Steuer viel Erfahrung abverlangen. Zwischen den H\u00fcgeln der Romagna entstanden, ist sie somit keine gew\u00f6hnliche Strecke: herrlich in die Natur des <strong>Parco delle Acque Minerali<\/strong> eingebettet, schmiegt sie sich an dessen Formen und schenkt den Zuschauern w\u00e4hrend des Rennens ein einzigartiges Schauspiel.<\/p>\n<h2>Hinter den Kulissen: Pit Lane Walk, Grid Walk und Autogrammstunde<\/h2>\n<figure class=\"wp-caption aligncenter\" style=\"max-width: 678px;\">\n<img decoding=\"async\" class=\"size-full wp-image-6581\" src=\"https:\/\/zampieravecchia.it\/wp-content\/uploads\/2026\/06\/prototipo-lmp2-elms-centro-imola.jpg\" alt=\"LMP2-Prototyp der European Le Mans Series, ausgestellt in der Altstadt von Imola\" width=\"678\" height=\"452\" srcset=\"https:\/\/zampieravecchia.it\/wp-content\/uploads\/2026\/06\/prototipo-lmp2-elms-centro-imola.jpg 678w, https:\/\/zampieravecchia.it\/wp-content\/uploads\/2026\/06\/prototipo-lmp2-elms-centro-imola-300x200.jpg 300w, https:\/\/zampieravecchia.it\/wp-content\/uploads\/2026\/06\/prototipo-lmp2-elms-centro-imola-600x400.jpg 600w\" sizes=\"(max-width: 678px) 100vw, 678px\" \/><figcaption class=\"wp-caption-text\">Ein LMP2-Prototyp der ELMS, ausgestellt in der Altstadt von Imola.<\/figcaption><\/figure>\n<p>Doch \u00fcber den Wettbewerb hinaus gibt es noch mehr: Es gibt einen Blick hinter die Kulissen, den es zu entdecken gilt. Der <strong>Pit Lane Walk<\/strong> ist die Gelegenheit, die Fahrzeuge und die Teams bei der Arbeit in den Boxen aus der N\u00e4he zu sehen, w\u00e4hrend der <strong>Grid Walk<\/strong> es erm\u00f6glicht, den Nervenkitzel direkt von der Startaufstellung aus zu erleben, mit einer einzigartigen Perspektive kurz vor dem Rennstart.<\/p>\n<p>Nachdem man ein so mitrei\u00dfendes Rennen verfolgt hat, ist es ganz normal, dass man denjenigen die Hand sch\u00fctteln m\u00f6chte, die es mit so viel Mut schaffen, diese Maschinen zu beherrschen. Die Veranstalter haben daran gedacht und die Begegnung mit den Fahrern in der ersehnten <strong>Autogrammstunde<\/strong> ins Tagesprogramm aufgenommen.<\/p>\n<h2>Wo Sie w\u00e4hrend der 4 Stunden von Imola 2026 in der N\u00e4he von Imola \u00fcbernachten<\/h2>\n<p>Werden Sie bei den <strong>4 Stunden von Imola 2026<\/strong> dabei sein und suchen noch eine Unterkunft? Das Wochenende der 4 Stunden von Imola ist eine Veranstaltung, die Tausende von Begeisterten aus aller Welt anzieht. Das Adrenalin des Autodromo Internazionale Enzo e Dino Ferrari ist ansteckend, doch nach einem Tag zwischen dem Dr\u00f6hnen der Motoren braucht es den richtigen Ort, um wieder zu Kr\u00e4ften zu kommen.<\/p>\n<p>Imola und seine Umgebung bieten verschiedene M\u00f6glichkeiten f\u00fcr jede Art von Besucher: <strong>Hotels im Zentrum<\/strong> f\u00fcr alle, die das st\u00e4dtische Flair erleben m\u00f6chten; <strong>B&amp;Bs und G\u00e4stezimmer<\/strong>, intimere und oft familiengef\u00fchrte Unterk\u00fcnfte; einladende <strong>Agriturismi<\/strong> mitten im Gr\u00fcnen.<\/p>\n<p>Suchen Sie einen Ort zum \u00dcbernachten in der N\u00e4he von Imola? Beenden Sie Ihre Suche und kommen Sie zu uns, um den Unterschied zu erleben, im <strong><a href=\"https:\/\/zampieravecchia.it\/de\/\">Podere Zampiera Vecchia di Imola<\/a><\/strong>: Hier finden Sie eine Atmosph\u00e4re, die die Sch\u00f6nheit des romagnolischen Landes widerspiegelt, gesund und echt, die Ihnen eine erholsame Nachtruhe garantiert.<\/p>\n<p><strong><a href=\"https:\/\/zampieravecchia.it\/de\/kontakt\/\">Buchen Sie jetzt Ihren Aufenthalt im Podere Zampiera Vecchia<\/a><\/strong><\/p>\n<p><em>Lesen Sie auch:<\/em> <a href=\"https:\/\/zampieravecchia.it\/de\/events-in-imola-2026\/\">Events in Imola 2026<\/a> &middot; <a href=\"https:\/\/zampieravecchia.it\/de\/imola-di-mercoledi-2026\/\">Imola di Mercoled\u00ec 2026<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die 4 Stunden von Imola 2026 (ELMS) am Autodromo Enzo e Dino Ferrari am 4.-5. Juli: wie das Langstreckenrennen funktioniert und wo Sie in der N\u00e4he der Rennstrecke \u00fcbernachten.<\/p>\n","protected":false},"author":1,"featured_media":6579,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[145],"tags":[],"class_list":["post-6808","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-deu"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>4 Stunden von Imola 2026: ELMS-Rennen &amp; \u00dcbernachten<\/title>\n<meta name=\"description\" content=\"Die European Le Mans Series kehrt am 4.-5. Juli 2026 nach Imola zur\u00fcck: das Rennen, die Klassen und wo Sie im Podere Zampiera Vecchia \u00fcbernachten.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zampieravecchia.it\/de\/4-stunden-von-imola-2026-european-le-mans-series\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"4 Stunden von Imola 2026: ELMS-Rennen &amp; \u00dcbernachten\" \/>\n<meta property=\"og:description\" content=\"Die European Le Mans Series kehrt am 4.-5. Juli 2026 nach Imola zur\u00fcck: das Rennen, die Klassen und wo Sie im Podere Zampiera Vecchia \u00fcbernachten.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zampieravecchia.it\/de\/4-stunden-von-imola-2026-european-le-mans-series\/\" \/>\n<meta property=\"og:site_name\" content=\"Zampiera Vecchia\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-20T11:13:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T22:21:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zampieravecchia.it\/wp-content\/uploads\/2026\/06\/4-ore-imola-2026-european-le-mans-series-partenza.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"678\" \/>\n\t<meta property=\"og:image:height\" content=\"452\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"M. Essence\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"M. Essence\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/zampieravecchia.it\\\/de\\\/4-stunden-von-imola-2026-european-le-mans-series\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zampieravecchia.it\\\/de\\\/4-stunden-von-imola-2026-european-le-mans-series\\\/\"},\"author\":{\"name\":\"M. Essence\",\"@id\":\"http:\\\/\\\/zampieravecchia.it\\\/de\\\/#\\\/schema\\\/person\\\/6f935517343634df04e56d8162f0dc27\"},\"headline\":\"4 Stunden von Imola 2026: Die European Le Mans Series kehrt zum Autodromo Enzo e Dino Ferrari zur\u00fcck\",\"datePublished\":\"2026-06-20T11:13:19+00:00\",\"dateModified\":\"2026-07-14T22:21:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/zampieravecchia.it\\\/de\\\/4-stunden-von-imola-2026-european-le-mans-series\\\/\"},\"wordCount\":739,\"image\":{\"@id\":\"https:\\\/\\\/zampieravecchia.it\\\/de\\\/4-stunden-von-imola-2026-european-le-mans-series\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zampieravecchia.it\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/4-ore-imola-2026-european-le-mans-series-partenza.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zampieravecchia.it\\\/de\\\/4-stunden-von-imola-2026-european-le-mans-series\\\/\",\"url\":\"https:\\\/\\\/zampieravecchia.it\\\/de\\\/4-stunden-von-imola-2026-european-le-mans-series\\\/\",\"name\":\"4 Stunden von Imola 2026: ELMS-Rennen & \u00dcbernachten\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/zampieravecchia.it\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zampieravecchia.it\\\/de\\\/4-stunden-von-imola-2026-european-le-mans-series\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zampieravecchia.it\\\/de\\\/4-stunden-von-imola-2026-european-le-mans-series\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zampieravecchia.it\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/4-ore-imola-2026-european-le-mans-series-partenza.jpg\",\"datePublished\":\"2026-06-20T11:13:19+00:00\",\"dateModified\":\"2026-07-14T22:21:14+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/zampieravecchia.it\\\/de\\\/#\\\/schema\\\/person\\\/6f935517343634df04e56d8162f0dc27\"},\"description\":\"Die European Le Mans Series kehrt am 4.-5. Juli 2026 nach Imola zur\u00fcck: das Rennen, die Klassen und wo Sie im Podere Zampiera Vecchia \u00fcbernachten.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zampieravecchia.it\\\/de\\\/4-stunden-von-imola-2026-european-le-mans-series\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zampieravecchia.it\\\/de\\\/4-stunden-von-imola-2026-european-le-mans-series\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/zampieravecchia.it\\\/de\\\/4-stunden-von-imola-2026-european-le-mans-series\\\/#primaryimage\",\"url\":\"https:\\\/\\\/zampieravecchia.it\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/4-ore-imola-2026-european-le-mans-series-partenza.jpg\",\"contentUrl\":\"https:\\\/\\\/zampieravecchia.it\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/4-ore-imola-2026-european-le-mans-series-partenza.jpg\",\"width\":678,\"height\":452,\"caption\":\"La partenza della 4 Ore di Imola sul circuito Enzo e Dino Ferrari.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zampieravecchia.it\\\/de\\\/4-stunden-von-imola-2026-european-le-mans-series\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/zampieravecchia.it\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"4 Stunden von Imola 2026: Die European Le Mans Series kehrt zum Autodromo Enzo e Dino Ferrari zur\u00fcck\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/zampieravecchia.it\\\/de\\\/#website\",\"url\":\"http:\\\/\\\/zampieravecchia.it\\\/de\\\/\",\"name\":\"Zampiera Vecchia\",\"description\":\"Agriturismo mit Pool bei Imola\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/zampieravecchia.it\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/zampieravecchia.it\\\/de\\\/#\\\/schema\\\/person\\\/6f935517343634df04e56d8162f0dc27\",\"name\":\"M. Essence\",\"sameAs\":[\"https:\\\/\\\/zampieravecchia.it\"],\"url\":\"https:\\\/\\\/zampieravecchia.it\\\/de\\\/author\\\/dzweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"4 Stunden von Imola 2026: ELMS-Rennen & \u00dcbernachten","description":"Die European Le Mans Series kehrt am 4.-5. Juli 2026 nach Imola zur\u00fcck: das Rennen, die Klassen und wo Sie im Podere Zampiera Vecchia \u00fcbernachten.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zampieravecchia.it\/de\/4-stunden-von-imola-2026-european-le-mans-series\/","og_locale":"de_DE","og_type":"article","og_title":"4 Stunden von Imola 2026: ELMS-Rennen & \u00dcbernachten","og_description":"Die European Le Mans Series kehrt am 4.-5. Juli 2026 nach Imola zur\u00fcck: das Rennen, die Klassen und wo Sie im Podere Zampiera Vecchia \u00fcbernachten.","og_url":"https:\/\/zampieravecchia.it\/de\/4-stunden-von-imola-2026-european-le-mans-series\/","og_site_name":"Zampiera Vecchia","article_published_time":"2026-06-20T11:13:19+00:00","article_modified_time":"2026-07-14T22:21:14+00:00","og_image":[{"width":678,"height":452,"url":"https:\/\/zampieravecchia.it\/wp-content\/uploads\/2026\/06\/4-ore-imola-2026-european-le-mans-series-partenza.jpg","type":"image\/jpeg"}],"author":"M. Essence","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"M. Essence","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/zampieravecchia.it\/de\/4-stunden-von-imola-2026-european-le-mans-series\/#article","isPartOf":{"@id":"https:\/\/zampieravecchia.it\/de\/4-stunden-von-imola-2026-european-le-mans-series\/"},"author":{"name":"M. Essence","@id":"http:\/\/zampieravecchia.it\/de\/#\/schema\/person\/6f935517343634df04e56d8162f0dc27"},"headline":"4 Stunden von Imola 2026: Die European Le Mans Series kehrt zum Autodromo Enzo e Dino Ferrari zur\u00fcck","datePublished":"2026-06-20T11:13:19+00:00","dateModified":"2026-07-14T22:21:14+00:00","mainEntityOfPage":{"@id":"https:\/\/zampieravecchia.it\/de\/4-stunden-von-imola-2026-european-le-mans-series\/"},"wordCount":739,"image":{"@id":"https:\/\/zampieravecchia.it\/de\/4-stunden-von-imola-2026-european-le-mans-series\/#primaryimage"},"thumbnailUrl":"https:\/\/zampieravecchia.it\/wp-content\/uploads\/2026\/06\/4-ore-imola-2026-european-le-mans-series-partenza.jpg","articleSection":["Blog"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/zampieravecchia.it\/de\/4-stunden-von-imola-2026-european-le-mans-series\/","url":"https:\/\/zampieravecchia.it\/de\/4-stunden-von-imola-2026-european-le-mans-series\/","name":"4 Stunden von Imola 2026: ELMS-Rennen & \u00dcbernachten","isPartOf":{"@id":"http:\/\/zampieravecchia.it\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zampieravecchia.it\/de\/4-stunden-von-imola-2026-european-le-mans-series\/#primaryimage"},"image":{"@id":"https:\/\/zampieravecchia.it\/de\/4-stunden-von-imola-2026-european-le-mans-series\/#primaryimage"},"thumbnailUrl":"https:\/\/zampieravecchia.it\/wp-content\/uploads\/2026\/06\/4-ore-imola-2026-european-le-mans-series-partenza.jpg","datePublished":"2026-06-20T11:13:19+00:00","dateModified":"2026-07-14T22:21:14+00:00","author":{"@id":"http:\/\/zampieravecchia.it\/de\/#\/schema\/person\/6f935517343634df04e56d8162f0dc27"},"description":"Die European Le Mans Series kehrt am 4.-5. Juli 2026 nach Imola zur\u00fcck: das Rennen, die Klassen und wo Sie im Podere Zampiera Vecchia \u00fcbernachten.","breadcrumb":{"@id":"https:\/\/zampieravecchia.it\/de\/4-stunden-von-imola-2026-european-le-mans-series\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zampieravecchia.it\/de\/4-stunden-von-imola-2026-european-le-mans-series\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/zampieravecchia.it\/de\/4-stunden-von-imola-2026-european-le-mans-series\/#primaryimage","url":"https:\/\/zampieravecchia.it\/wp-content\/uploads\/2026\/06\/4-ore-imola-2026-european-le-mans-series-partenza.jpg","contentUrl":"https:\/\/zampieravecchia.it\/wp-content\/uploads\/2026\/06\/4-ore-imola-2026-european-le-mans-series-partenza.jpg","width":678,"height":452,"caption":"La partenza della 4 Ore di Imola sul circuito Enzo e Dino Ferrari."},{"@type":"BreadcrumbList","@id":"https:\/\/zampieravecchia.it\/de\/4-stunden-von-imola-2026-european-le-mans-series\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/zampieravecchia.it\/de\/"},{"@type":"ListItem","position":2,"name":"4 Stunden von Imola 2026: Die European Le Mans Series kehrt zum Autodromo Enzo e Dino Ferrari zur\u00fcck"}]},{"@type":"WebSite","@id":"http:\/\/zampieravecchia.it\/de\/#website","url":"http:\/\/zampieravecchia.it\/de\/","name":"Zampiera Vecchia","description":"Agriturismo mit Pool bei Imola","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/zampieravecchia.it\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"http:\/\/zampieravecchia.it\/de\/#\/schema\/person\/6f935517343634df04e56d8162f0dc27","name":"M. Essence","sameAs":["https:\/\/zampieravecchia.it"],"url":"https:\/\/zampieravecchia.it\/de\/author\/dzweb\/"}]}},"_links":{"self":[{"href":"https:\/\/zampieravecchia.it\/de\/wp-json\/wp\/v2\/posts\/6808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zampieravecchia.it\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zampieravecchia.it\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zampieravecchia.it\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zampieravecchia.it\/de\/wp-json\/wp\/v2\/comments?post=6808"}],"version-history":[{"count":2,"href":"https:\/\/zampieravecchia.it\/de\/wp-json\/wp\/v2\/posts\/6808\/revisions"}],"predecessor-version":[{"id":6818,"href":"https:\/\/zampieravecchia.it\/de\/wp-json\/wp\/v2\/posts\/6808\/revisions\/6818"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zampieravecchia.it\/de\/wp-json\/wp\/v2\/media\/6579"}],"wp:attachment":[{"href":"https:\/\/zampieravecchia.it\/de\/wp-json\/wp\/v2\/media?parent=6808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zampieravecchia.it\/de\/wp-json\/wp\/v2\/categories?post=6808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zampieravecchia.it\/de\/wp-json\/wp\/v2\/tags?post=6808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}